{"id":14,"count":5,"description":"","link":"https:\/\/tiempoensalud.cl\/grado\/category\/entradas\/paolo-fuentealba\/","name":"Paolo Fuentealba","slug":"paolo-fuentealba","taxonomy":"category","parent":13,"meta":[],"_links":{"self":[{"href":"https:\/\/tiempoensalud.cl\/grado\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiempoensalud.cl\/grado\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tiempoensalud.cl\/grado\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/tiempoensalud.cl\/grado\/wp-json\/wp\/v2\/categories\/13"}],"wp:post_type":[{"href":"https:\/\/tiempoensalud.cl\/grado\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}